{"id":477,"date":"2022-07-22T13:16:40","date_gmt":"2022-07-22T11:16:40","guid":{"rendered":"https:\/\/www.voicearchive.com\/de-de\/?p=477"},"modified":"2022-07-25T08:01:18","modified_gmt":"2022-07-25T06:01:18","slug":"die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte","status":"publish","type":"post","link":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/","title":{"rendered":"Die Sinfonie einer Pandemie oder wie unser Ton- und Audiokonsum eine ganze Branche ver\u00e4nderte"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[48,49],"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vertonung-fuer-werbungen","category-werbesprecher-werbestimmen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.7 (Yoast SEO v20.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die Sinfonie einer Pandemie - Voicearchive<\/title>\n<meta name=\"description\" content=\"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Sinfonie einer Pandemie oder wie unser Ton- und Audiokonsum eine ganze Branche ver\u00e4nderte\" \/>\n<meta property=\"og:description\" content=\"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/\" \/>\n<meta property=\"og:site_name\" content=\"Voicearchive DE\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T11:16:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T06:01:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.voicearchive.com\/de-de\/wp-content\/uploads\/sites\/3\/2022\/07\/RE-COLOURED-musical-instruments-01-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1702\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"voicearchive\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"voicearchive\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/\",\"url\":\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/\",\"name\":\"Die Sinfonie einer Pandemie - Voicearchive\",\"isPartOf\":{\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/#website\"},\"datePublished\":\"2022-07-22T11:16:40+00:00\",\"dateModified\":\"2022-07-25T06:01:18+00:00\",\"author\":{\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/6185352b9c73a4c50709f050912308b5\"},\"description\":\"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?\",\"breadcrumb\":{\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Titelseite\",\"item\":\"https:\/\/www.voicearchive.com\/de-de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vertonung f\u00fcr Werbungen\",\"item\":\"https:\/\/www.voicearchive.com\/de-de\/blog\/kategorie\/vertonung-fuer-werbungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Die Sinfonie einer Pandemie oder wie unser Ton- und Audiokonsum eine ganze Branche ver\u00e4nderte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/#website\",\"url\":\"https:\/\/www.voicearchive.com\/de-de\/\",\"name\":\"Voicearchive DE\",\"description\":\"Finden Sie \u00fcber 2100 professionelle Sprecher \u2013 schnell und einfach\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.voicearchive.com\/de-de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/6185352b9c73a4c50709f050912308b5\",\"name\":\"voicearchive\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b89b2afb8d68ba43df97cd01ddab156e1cf679d5ab7666fe88c1c1a21e63d34a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b89b2afb8d68ba43df97cd01ddab156e1cf679d5ab7666fe88c1c1a21e63d34a?s=96&d=mm&r=g\",\"caption\":\"voicearchive\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Sinfonie einer Pandemie - Voicearchive","description":"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/","og_locale":"de_DE","og_type":"article","og_title":"Die Sinfonie einer Pandemie oder wie unser Ton- und Audiokonsum eine ganze Branche ver\u00e4nderte","og_description":"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?","og_url":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/","og_site_name":"Voicearchive DE","article_published_time":"2022-07-22T11:16:40+00:00","article_modified_time":"2022-07-25T06:01:18+00:00","og_image":[{"width":2560,"height":1702,"url":"https:\/\/www.voicearchive.com\/de-de\/wp-content\/uploads\/sites\/3\/2022\/07\/RE-COLOURED-musical-instruments-01-scaled.jpg","type":"image\/jpeg"}],"author":"voicearchive","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"voicearchive"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/","url":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/","name":"Die Sinfonie einer Pandemie - Voicearchive","isPartOf":{"@id":"https:\/\/www.voicearchive.com\/de-de\/#website"},"datePublished":"2022-07-22T11:16:40+00:00","dateModified":"2022-07-25T06:01:18+00:00","author":{"@id":"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/6185352b9c73a4c50709f050912308b5"},"description":"Der steigende Audiokonsum durch die Pandemie markiert den Beginn einer neuen \u00c4ra, in der der Ton dominiert. Ist Ihr Firma darauf vorbereitet?","breadcrumb":{"@id":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.voicearchive.com\/de-de\/blog\/die-sinfonie-einer-pandemie-oder-wie-unser-ton-und-audiokonsum-eine-ganze-branche-veraenderte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Titelseite","item":"https:\/\/www.voicearchive.com\/de-de\/"},{"@type":"ListItem","position":2,"name":"Vertonung f\u00fcr Werbungen","item":"https:\/\/www.voicearchive.com\/de-de\/blog\/kategorie\/vertonung-fuer-werbungen\/"},{"@type":"ListItem","position":3,"name":"Die Sinfonie einer Pandemie oder wie unser Ton- und Audiokonsum eine ganze Branche ver\u00e4nderte"}]},{"@type":"WebSite","@id":"https:\/\/www.voicearchive.com\/de-de\/#website","url":"https:\/\/www.voicearchive.com\/de-de\/","name":"Voicearchive DE","description":"Finden Sie \u00fcber 2100 professionelle Sprecher \u2013 schnell und einfach","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.voicearchive.com\/de-de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/6185352b9c73a4c50709f050912308b5","name":"voicearchive","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.voicearchive.com\/de-de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b89b2afb8d68ba43df97cd01ddab156e1cf679d5ab7666fe88c1c1a21e63d34a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b89b2afb8d68ba43df97cd01ddab156e1cf679d5ab7666fe88c1c1a21e63d34a?s=96&d=mm&r=g","caption":"voicearchive"}}]}},"_links":{"self":[{"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/media\/478"}],"wp:attachment":[{"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.voicearchive.com\/de-de\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}